{"id":30,"count":29,"description":"","link":"https:\/\/artigonews.com\/es\/category\/aplicativos\/","name":"Aplicaciones","slug":"aplicaciones","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/artigonews.com\/es\/wp-json\/wp\/v2\/categories\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/artigonews.com\/es\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/artigonews.com\/es\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/artigonews.com\/es\/wp-json\/wp\/v2\/posts?categories=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}